{"id":2620,"date":"2022-03-18T07:42:39","date_gmt":"2022-03-18T07:42:39","guid":{"rendered":"https:\/\/indigo-horizon.com\/pt\/?p=2620"},"modified":"2022-05-20T12:44:47","modified_gmt":"2022-05-20T12:44:47","slug":"epileptic-seizure-frequency-fell-by-86-in-kids-treated-with-medicinal-cannabis","status":"publish","type":"post","link":"https:\/\/indigo-horizon.com\/pt\/epileptic-seizure-frequency-fell-by-86-in-kids-treated-with-medicinal-cannabis\/","title":{"rendered":"Frequ\u00eancia de crise epil\u00e9tica desceu cerca de 86% em crian\u00e7as tratadas com can\u00e1bis medicinal"},"content":{"rendered":"<section id=\"bt_section6a982caf8cf38\"  class=\"boldSection gutter\" ><div class=\"port\"><div class=\"boldCell\"><div class=\"boldCellInner\"><div class=\"boldRow  \" ><div class=\"boldRowInner\"><div class=\"rowItem col-md-12 col-ms-12  btTextLeft\"  ><div class=\"rowItemContent\" ><div class=\"btText\" ><p>A cannabis medicinal de planta inteira inclui tetra-hidrocanabinol ou THC, o principal ingrediente ativo da planta que \u00e9 respons\u00e1vel pela caracter\u00edstica \u201calta\u201d associada ao uso recreativo, al\u00e9m de canabidiol, outros canabin\u00f3ides neuroativos e mol\u00e9culas como terpenos.<\/p>\n<p>O estudo descobriu que nenhuma das crian\u00e7as respondeu a outros tratamentos al\u00e9m da cannabis medicinal, incluindo o \u00fanico produto de canabidiol (CBD) licenciado para sua condi\u00e7\u00e3o.<\/p>\n<p>As descobertas levaram os pesquisadores a pedir uma maior explora\u00e7\u00e3o dos potenciais benef\u00edcios terap\u00eauticos dos produtos de cannabis medicinal de plantas inteiras. Evid\u00eancias aned\u00f3ticas substanciais sobre o valor da cannabis medicinal para o tratamento de epilepsias infantis v\u00eam se acumulando desde 1800, dizem os pesquisadores. Mas n\u00e3o h\u00e1 muitas evid\u00eancias cient\u00edficas recentes sobre a efic\u00e1cia dos extratos de cannabis de plantas inteiras.<\/p>\n<\/div><div class=\"btClear btSeparator topSmallSpaced noBorder\" ><hr><\/div><header class=\"header btClear medium btDash bottomDash  btNormalDash\" ><div class=\"dash\"><h3><span class=\"headline\">Cannabis medicinal para tratar a epilepsia<\/span><\/h3><\/div><\/header><div class=\"btText\" ><p>A cannabis recreativa e medicinal foi ilegalizada no Reino Unido sob o<a href=\"https:\/\/www.legislation.gov.uk\/ukpga\/1971\/38\/contents\" target=\"_blank\" rel=\"noopener\">Misuse of Drugs Act 1971<\/a>; portanto, a pesquisa de cannabis cessou em grande parte, explicaram os pesquisadores.<\/p>\n<p>No entanto, os pais cujos filhos responderam bem aos extratos de cannabis medicinal de plantas inteiras foram designados como um medicamento de prescri\u00e7\u00e3o para o tratamento da epilepsia infantil grave em 2018. Este medicamento foi prescrito quando os medicamentos antiepil\u00e9pticos convencionais ou o canabidiol purificado (\u00f3leo CBD) n\u00e3o foram eficazes.<\/p>\n<p>Mas os m\u00e9dicos do Reino Unido t\u00eam relutado em prescrever isso para crian\u00e7as com epilepsia grave, em grande parte devido \u00e0 falta de dados confirmat\u00f3rios de ensaios cl\u00ednicos.<\/p>\n<p>O Instituto <a href=\"https:\/\/www.nice.org.uk\/\" target=\"_blank\" rel=\"noopener\">National Institute for Health and Clinical Excellence (NICE)<\/a>\u00a0 do Reino Unido, que fornece orienta\u00e7\u00f5es sobre quais tratamentos e terapias o servi\u00e7o de sa\u00fade da Inglaterra deve adotar, aceitou que dados do mundo real, incluindo s\u00e9ries de casos, s\u00e3o fontes v\u00e1lidas de evid\u00eancia, especialmente quando sua dif\u00edcil realizar ensaios cl\u00ednicos, por exemplo, em crian\u00e7as.<\/p>\n<p>Os pesquisadores avaliaram o uso de cannabis medicinal de planta inteira em 10 crian\u00e7as cuja epilepsia grave n\u00e3o respondeu ao tratamento convencional e duas das quais n\u00e3o responderam ao \u00fanico \u00f3leo de CBD purificado de grau farmac\u00eautico licenciado para a condi\u00e7\u00e3o em crian\u00e7as (Epidyolex).<\/p>\n<p>Al\u00e9m disso, os pesquisadores queriam avaliar a mudan\u00e7a percentual na frequ\u00eancia mensal de convuls\u00f5es e o impacto da cannabis medicinal nas mudan\u00e7as no uso de drogas convencionais para epilepsia. Eles tamb\u00e9m queriam relatar os pontos fortes e as doses usadas e os custos incorridos.<\/p>\n<\/div><div class=\"btClear btSeparator topSmallSpaced noBorder\" ><hr><\/div><header class=\"header btClear medium btDash bottomDash  btNormalDash\" ><div class=\"dash\"><h3><span class=\"headline\">O estudo<\/span><\/h3><\/div><\/header><div class=\"btText\" ><p>Todos os participantes foram recrutados de duas institui\u00e7\u00f5es de caridade que representam crian\u00e7as que usam cannabis medicinal para tratar sua <a href=\"https:\/\/www.healtheuropa.com\/neuron-discovery-could-contribute-to-improved-epilepsy-treatment\/108422\/\" target=\"_blank\" rel=\"noopener\">epilepsy<\/a> grave. A idade m\u00e9dia das crian\u00e7as era de seis anos, mas variou de um a 13 anos. Eles tinham uma s\u00e9rie de epilepsias e tr\u00eas tinham outros problemas concomitantes, incluindo espasmos infantis, dificuldades de aprendizagem e atraso global no desenvolvimento.<\/p>\n<p>Os dados foram coletados de seus pais ou respons\u00e1veis \u200b\u200bpor telefone ou videoconfer\u00eancia entre janeiro e maio de 2021.<\/p>\n<p>As crian\u00e7as j\u00e1 haviam experimentado uma m\u00e9dia de sete medicamentos convencionais para epilepsia. Depois de tomar cannabis medicinal, isso caiu para uma m\u00e9dia de um cada, com sete das crian\u00e7as parando completamente.<\/p>\n<p>Os pesquisadores descobriram que a frequ\u00eancia mensal de convuls\u00f5es foi reduzida para todas as 10 crian\u00e7as em uma m\u00e9dia geral de 86%.<\/p>\n<p>A an\u00e1lise qu\u00edmica completa de todos os produtos de cannabis medicinal usados \u200b\u200best\u00e1 em andamento, mas os pesquisadores conseguiram avaliar o conte\u00fado de THC e CBD. Isso mostrou que as crian\u00e7as tomaram uma m\u00e9dia de 5,15 mg de THC e 171,8 mg de CBD todos os dias.<\/p>\n<p>O custo m\u00e9dio mensal dos produtos de cannabis medicinal foi de \u00a3 874. Uma crian\u00e7a obteve sua receita gratuitamente no NHS.<\/p>\n<p>Pais e cuidadores relataram melhorias significativas na sa\u00fade e bem-estar de seus filhos, inclusive no sono, alimenta\u00e7\u00e3o, comportamento e cogni\u00e7\u00e3o, depois que come\u00e7aram a tomar todos os produtos de cannabis medicinal da planta. Apenas alguns efeitos colaterais menores, como cansa\u00e7o, foram relatados.<\/p>\n<p>Este \u00e9 um estudo observacional envolvendo um pequeno n\u00famero de participantes. E os pesquisadores reconheceram que era retrospectivo e se baseava na lembran\u00e7a dos pais, sem grupo comparador. E \u00e9 poss\u00edvel que apenas os pais nos quais a cannabis medicinal funcionou bem decidiram participar.<\/p>\n<p>Mas os pesquisadores destacaram que suas descobertas est\u00e3o alinhadas com v\u00e1rios estudos de interven\u00e7\u00e3o observacionais e controlados que mostram redu\u00e7\u00f5es significativas na frequ\u00eancia de convuls\u00f5es ap\u00f3s o tratamento com cannabis medicinal.<\/p>\n<p>Os novos dados sugeriram que os produtos de cannabis medicinal de planta inteira s\u00e3o mais eficazes do que os produtos de CBD.<\/p>\n<p>\u201cMais pesquisas s\u00e3o necess\u00e1rias para elucidar os mecanismos pelos quais os respectivos constituintes aditivos de produtos vegetais inteiros levam a resultados cl\u00ednicos superiores\u201d, comentaram os pesquisadores.<\/p>\n<p>E isso deve incluir a compara\u00e7\u00e3o dos efeitos indesejados da cannabis medicinal de planta inteira com os efeitos nocivos conhecidos dos medicamentos convencionais para a epilepsia, dizem eles.<\/p>\n<p>Mas eles conclu\u00edram: \u201cAcreditamos que nossos dados sobre cannabis medicinal de planta inteira na epilepsia resistente ao tratamento grave com in\u00edcio na inf\u00e2ncia fornecem evid\u00eancias para apoiar sua introdu\u00e7\u00e3o no NHS dentro das diretrizes atuais de prescri\u00e7\u00e3o do NICE.<\/p>\n<p>\u201cTal medida seria extremamente ben\u00e9fica para as fam\u00edlias, que, al\u00e9m de ter o sofrimento psicol\u00f3gico de cuidar de seus filhos com doen\u00e7as cr\u00f4nicas, tamb\u00e9m precisam cobrir o encargo financeiro incapacitante de seus medicamentos\u201d.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Um novo estudo concluiu que a frequ\u00eancia de crise epil\u00e9tica desceu em m\u00e9dia 86% em 10 crian\u00e7as tratadas com can\u00e1bis medicinal derivado s\u00f3 da planta.<\/p>\n","protected":false},"author":1,"featured_media":2621,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,94],"tags":[96,97],"class_list":["post-2620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","category-medicinal-cannabis","tag-medicinal-cannabis","tag-medicinal-cannabis-industry"],"_links":{"self":[{"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/posts\/2620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/comments?post=2620"}],"version-history":[{"count":6,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/posts\/2620\/revisions"}],"predecessor-version":[{"id":2811,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/posts\/2620\/revisions\/2811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/media\/2621"}],"wp:attachment":[{"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/media?parent=2620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/categories?post=2620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indigo-horizon.com\/pt\/wp-json\/wp\/v2\/tags?post=2620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}